{"id":1227,"date":"2019-10-31T08:48:24","date_gmt":"2019-10-31T08:48:24","guid":{"rendered":"https:\/\/bestvision.group\/home\/responsibility\/"},"modified":"2020-03-23T13:40:18","modified_gmt":"2020-03-23T13:40:18","slug":"responsibility","status":"publish","type":"page","link":"https:\/\/bestvision.group\/fr\/home\/responsibility\/","title":{"rendered":"Responsibility"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Notes juridiques<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Conditions d&rsquo;utilisation<\/h2>\n\n\n\n<p>Le site bestvision.group est la propri\u00e9t\u00e9 exclusive de Best Vision Group, (ci-apr\u00e8s d\u00e9nomm\u00e9 \u00ab\u00a0Best Vision\u00a0\u00bb ou \u00ab\u00a0Best Vision Group\u00a0\u00bb). L&rsquo;acc\u00e8s et la navigation sur le site par les utilisateurs individuels sont gratuits et soumis \u00e0 l&rsquo;acceptation des termes et conditions des pr\u00e9sentes mentions l\u00e9gales. L&rsquo;utilisateur reconna\u00eet et, en tout cas, accepte : (i) que Best Vision se r\u00e9serve le droit de modifier les termes et conditions de ces notes l\u00e9gales \u00e0 tout moment, en communiquant les modifications aux utilisateurs au moyen d&rsquo;une note g\u00e9n\u00e9rale jointe au site ou au moyen d&rsquo;un lien vers cette note et (ii) qu&rsquo;\u00e0 partir du moment de chaque note g\u00e9n\u00e9rale maintenant mentionn\u00e9e, les notes l\u00e9gales modifi\u00e9es constitueront les nouveaux termes et conditions pour acc\u00e9der et naviguer sur le site (ces notes l\u00e9gales, comme progressivement les \u00ab\u00a0Notes L\u00e9gales\u00a0\u00bb sont soumises \u00e0 une modification potentielle continue). <\/p>\n\n\n\n<p><strong>Droit applicable<\/strong><\/p>\n\n\n\n<p>Pour l&rsquo;Europe, les notes juridiques sont r\u00e9gies par le droit suisse, le For est \u00e0 Gen\u00e8ve. <br>Pour l&rsquo;Am\u00e9rique, les notes juridiques sont r\u00e9gies par le droit des \u00c9tats-Unis d&rsquo;Am\u00e9rique, le For est \u00e0 Miami.<br>Pour l&rsquo;Afrique, les notes juridiques sont r\u00e9gies par le droit suisse, le For est \u00e0 Gen\u00e8ve. <br>Pour l&rsquo;Asie, les notes juridiques sont r\u00e9gies par le droit suisse, le For est \u00e0 Gen\u00e8ve. <br>Pour l&rsquo;Australie, les notes juridiques sont r\u00e9gies par le droit des \u00c9tats-Unis d&rsquo;Am\u00e9rique, le For est \u00e0 Miami. <\/p>\n\n\n\n<p><strong>Droits de propri\u00e9t\u00e9 intellectuelle<\/strong><\/p>\n\n\n\n<p>\u2022          Le contenu du site, \u00e0 titre d&rsquo;exemple et non exhaustif, les \u0153uvres, images, photographies, dialogues, musiques, sons, vid\u00e9os, textes et tout autre mat\u00e9riel sous quelque format que ce soit, y compris, \u00e0 titre d&rsquo;exemple et non exhaustif, les menus, les pages web, les graphiques, les couleurs, les sch\u00e9mas, les outils, les personnages, le design, les diagrammes, les dessins, les m\u00e9thodes, les processus, fonctions et logiciels (individuellement et\/ou collectivement \u00a0\u00bb Contenu \u00ab\u00a0) ainsi que les signes et\/ou logos distinctifs correspondants sont la propri\u00e9t\u00e9 exclusive de BestVision ou de sa disponibilit\u00e9 exclusive, et ne peuvent en aucun cas \u00eatre utilis\u00e9s de quelque mani\u00e8re que ce soit et\/ou sous quelque forme que ce soit sans l&rsquo;accord \u00e9crit pr\u00e9alable de BestVision. Sauf mention contraire expresse sur le site, le Contenu peut \u00eatre visualis\u00e9 et\/ou \u00e9cout\u00e9 uniquement en mode &lsquo;Streaming&rsquo;. \u00ab\u00a0streaming\u00a0\u00bb signifie  la modalit\u00e9 de visualisation et\/ou d&rsquo;\u00e9coute des contenus en temps r\u00e9el et sans n\u00e9cessit\u00e9 et\/ou possibilit\u00e9 de reproduction, temporaire ou permanente, de distribution, de redistribution, de communication au public ou d&rsquo;une autre utilisation, sous une forme ou une autre que le \u00ab\u00a0streaming\u00a0\u00bb d\u00e9fini ci-dessus.   <br> \u2022        Dans le cas o\u00f9 des codes de lien sont fournis sur le site d&rsquo;incorporation li\u00e9s \u00e0 des contenus sp\u00e9cifiques, ces codes peuvent \u00eatre utilis\u00e9s par les utilisateurs uniquement pour leur propre usage direct, personnel et priv\u00e9 et tant que l&rsquo;utilisation susmentionn\u00e9e ne soit pas \u00e0 des fins directement ou indirectement, commerciales et \/ ou \u00e0 des fins de profit.   <br> \u2022        Toute utilisation des codes et\/ou du contenu en violation des limites indiqu\u00e9es dans les Notes L\u00e9gales, ou autrement contraire \u00e0 la loi, est ill\u00e9gale et, par cons\u00e9quent, sera d\u00e9nonc\u00e9e par BestVision aux autorit\u00e9s comp\u00e9tentes.   <br> \u2022        Les marques d\u00e9pos\u00e9es et les logos BestVision, y compris le nom de domaine bestvision.group, sont disponibles exclusivement pour BestVision ou pour les soci\u00e9t\u00e9s du groupe BestVision. Ces marques d\u00e9pos\u00e9es, logos et domaines ne peuvent \u00eatre utilis\u00e9s de quelque mani\u00e8re que ce soit sans l&rsquo;accord \u00e9crit pr\u00e9alable de BestVision.<\/p>\n\n\n\n<p><strong>Liens vers d&rsquo;autres sites web<\/strong><\/p>\n\n\n\n<p>\u2022        Le site peut contenir des liens contextuels (les \u00a0\u00bb liens \u00ab\u00a0) vers d&rsquo;autres sites Web qui n&rsquo;ont aucun lien avec le site de BestVision. BestVision ne contr\u00f4le ni ne supervise ces sites Internet, leur contenu et leurs r\u00e8gles.   <br> \u2022        Tout lien vers d&rsquo;autres sites Web ne doit pas \u00eatre compris de quelque mani\u00e8re que ce soit comme une activit\u00e9 de BestVision visant \u00e0 promouvoir ces sites et\/ou le contenu qui y est publi\u00e9.<\/p>\n\n\n\n<p><strong>Cookies<\/strong><\/p>\n\n\n\n<p>Le site peut contenir des cookies de session (qui ne sont pas stock\u00e9s de fa\u00e7on permanente sur l&rsquo;ordinateur de l&rsquo;utilisateur et qui disparaissent lorsqu&rsquo;il ferme le navigateur) pour permettre aux utilisateurs de mieux utiliser le site. Pour recevoir des cookies peut configurer votre navigateur dans l&rsquo;intention d&rsquo;\u00eatre averti de la pr\u00e9sence de cookies et d\u00e9cider ensuite de les accepter ou non. Le navigateur aussi peut \u00eatre configur\u00e9 pour rejeter automatiquement tous les cookies; dans ce cas, il est toutefois possible que l&rsquo;utilisateur ne puisse pas acc\u00e9der \u00e0 tous les services disponibles sur le site.<\/p>\n\n\n\n<p><strong>Limitations de responsabilit\u00e9<\/strong><\/p>\n\n\n\n<p>\u2022        L&rsquo;utilisateur reconna\u00eet et accepte que son acc\u00e8s et sa navigation sur le site se font \u00e0 ses propres risques et sous sa responsabilit\u00e9 exclusive.   <br> \u2022        L&rsquo;utilisateur reconna\u00eet et accepte \u00e9galement que le site est fourni \u00a0\u00bb tel quel \u00a0\u00bb et \u00a0\u00bb tel que disponible \u00a0\u00bb et qu&rsquo;il peut \u00eatre temporairement inaccessible ou contenir des d\u00e9fauts ou \u00eatre victime  de probl\u00e8mes de performance.   <br> \u2022        Best Vision n&rsquo;assume aucune responsabilit\u00e9 pour le contenu, les mat\u00e9riels  et\/ou les informations saisis sur le site par les utilisateurs dans les espaces virtuels des programmes que BestVision met \u00e0 disposition des utilisateurs pour l&rsquo;interaction avec le site (\u00a0\u00bb Contenu Utilisateur \u00ab\u00a0).   <br> \u2022        Best Vision ne sera pas responsable de toute perte ou dommage r\u00e9sultant de ou li\u00e9 de quelque mani\u00e8re que ce soit \u00e0 l&rsquo;utilisation ou au fonctionnement du site, y compris, entre autres, les dommages pour perte d&rsquo;activit\u00e9, perte de profits\/gains, interruption d&rsquo;activit\u00e9, perte d&rsquo;informations commerciales et\/ou tout autre type de perte p\u00e9cuniaire, sauf en cas de faute intentionnelle ou de n\u00e9gligence grave de Best Vision.<\/p>\n\n\n\n<p><strong>Rapport d&rsquo;abus<\/strong><\/p>\n\n\n\n<p>\u2022        Les utilisateurs qui ont identifi\u00e9 tout Contenu qu&rsquo;ils consid\u00e8rent ill\u00e9gal, inappropri\u00e9, offensant en informent imm\u00e9diatement Best Vision, en remplissant le formulaire de signalement d&rsquo;abus disponible sur le site, en bas de la page d&rsquo;accueil.   <br> \u2022        L&rsquo;utilisateur est invit\u00e9 \u00e0 une utilisation responsable de ses communications et partage d\u2019information. Les communications qui s&rsquo;av\u00e8rent infond\u00e9es et\/ou ill\u00e9gitimes seront de votre  responsabilit\u00e9.<\/p>\n\n\n\n<p><strong>Droit applicable<\/strong><\/p>\n\n\n\n<p>Les notes juridiques sont r\u00e9gies par le droit suisse,  For de Gen\u00e8ve  . <br>Best Vision Group.<\/p>\n","protected":false},"excerpt":{"rendered":"Notes juridiques Conditions d&rsquo;utilisation Le site bestvision.group est la propri\u00e9t\u00e9 exclusive de Best Vision Group, (ci-apr\u00e8s d\u00e9nomm\u00e9 \u00ab\u00a0Best Vision\u00a0\u00bb ou \u00ab\u00a0Best Vision Group\u00a0\u00bb). L&rsquo;acc\u00e8s et la navigation sur le site par les utilisateurs individuels sont gratuits et soumis \u00e0 l&rsquo;acceptation des termes et conditions des pr\u00e9sentes mentions l\u00e9gales. L&rsquo;utilisateur reconna\u00eet et, en tout cas, accepte&#8230; <a class=\"view-article\" href=\"https:\/\/bestvision.group\/fr\/home\/responsibility\/\">Voir l&rsquo;article<\/a>","protected":false},"author":4,"featured_media":0,"parent":1192,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"responsibility.php","meta":{"footnotes":""},"class_list":["post-1227","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/pages\/1227"}],"collection":[{"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/comments?post=1227"}],"version-history":[{"count":0,"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/pages\/1227\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/pages\/1192"}],"wp:attachment":[{"href":"https:\/\/bestvision.group\/fr\/wp-json\/wp\/v2\/media?parent=1227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}